{"id":753,"date":"2023-10-21T23:25:19","date_gmt":"2023-10-21T23:25:19","guid":{"rendered":"https:\/\/www.olekwitt.de\/?p=753"},"modified":"2023-10-21T23:25:19","modified_gmt":"2023-10-21T23:25:19","slug":"szymborska-projekt-2","status":"publish","type":"post","link":"https:\/\/www.olekwitt.de\/en\/szymborska-projekt-2\/","title":{"rendered":"Szymborska Projekt"},"content":{"rendered":"<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5-566x800.jpg\" alt=\"\" class=\"wp-image-769\" width=\"838\" height=\"1184\" srcset=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5-566x800.jpg 566w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5-212x300.jpg 212w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5-768x1086.jpg 768w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5-1086x1536.jpg 1086w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/10\/Kopia-_-Kopia-_-Hauptstr.-Performance-5.jpg 1414w\" sizes=\"(max-width: 838px) 100vw, 838px\" \/><\/figure>\n\n\n\n<p><strong>In einem leerstehenden Raum erforschten verschiedenen K\u00fcnstlerinnen zwei Wochen lang die Gedichte der polnischen Nobelpreistr\u00e4gerin Wislawa Szymborska. Nach dem Konzept von Olek Witt entstanden w\u00e4hrend dieser Zeit beeindruckende Tableaus vivant, Installationen und kurze Choreografien.<\/strong><\/p>\n\n\n\n<p><strong>Durch die Kombination von Tanz, Rezitationen und Live-Musik wurde eine fesselnde Performance geschaffen, in der die tiefgr\u00fcndigen und oft philosophischen Gedanken von Szymborska mit dem Publikum am 22.10.23 geteilt werden. Ein einzigartiges und einmaliges Kunstwerk, in dem die Leere mit Poesie gef\u00fcllt wird.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"566\" height=\"800\" src=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23-566x800.jpg\" alt=\"\" class=\"wp-image-754\" srcset=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23-566x800.jpg 566w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23-212x300.jpg 212w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23-768x1086.jpg 768w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23-1086x1536.jpg 1086w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/Szymborska-Projekt-am-27.08.23.jpg 1414w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/1-1024x576.jpg\" alt=\"\" class=\"wp-image-755\" srcset=\"https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/1-1024x576.jpg 1024w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/1-533x300.jpg 533w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/1-768x432.jpg 768w, https:\/\/www.olekwitt.de\/wp-content\/uploads\/2023\/08\/1.jpg 1473w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>In einem leerstehenden Raum erforschten verschiedenen K\u00fcnstlerinnen zwei Wochen lang die Gedichte der polnischen Nobelpreistr\u00e4gerin Wislawa Szymborska. Nach dem Konzept von Olek Witt entstanden w\u00e4hrend dieser Zeit beeindruckende Tableaus vivant, Installationen und kurze Choreografien. Durch die Kombination von Tanz, Rezitationen und Live-Musik wurde eine fesselnde Performance geschaffen, in der die tiefgr\u00fcndigen und oft philosophischen Gedanken [&hellip;]<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[8,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/posts\/753"}],"collection":[{"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/comments?post=753"}],"version-history":[{"count":3,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/posts\/753\/revisions"}],"predecessor-version":[{"id":770,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/posts\/753\/revisions\/770"}],"wp:attachment":[{"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/media?parent=753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/categories?post=753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.olekwitt.de\/en\/wp-json\/wp\/v2\/tags?post=753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}